{"id":6368,"date":"2020-01-03T13:10:08","date_gmt":"2020-01-03T12:10:08","guid":{"rendered":"http:\/\/localhost\/apps\/kinodvor\/index.php\/film\/krvavi-mesec\/"},"modified":"2020-01-03T13:40:10","modified_gmt":"2020-01-03T12:40:10","slug":"krvavi-mesec","status":"publish","type":"movie","link":"https:\/\/www.kinodvor.org\/en\/film\/krvavi-mesec\/","title":{"rendered":"Krvavi mesec"},"content":{"rendered":"<p>10.03.1970 &#8211; 17.03.1970 (2)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>premiera ameri\u0161kega westerna<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.kinodvor.org\/en\/wp-json\/wp\/v2\/movies\/6368"}],"collection":[{"href":"https:\/\/www.kinodvor.org\/en\/wp-json\/wp\/v2\/movies"}],"about":[{"href":"https:\/\/www.kinodvor.org\/en\/wp-json\/wp\/v2\/types\/movie"}],"wp:attachment":[{"href":"https:\/\/www.kinodvor.org\/en\/wp-json\/wp\/v2\/media?parent=6368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}